{"id":3129,"date":"2021-11-15T14:48:58","date_gmt":"2021-11-15T14:48:58","guid":{"rendered":"https:\/\/www.https:\/\/zozo.buyee.jp\/\/news\/?p=3129"},"modified":"2021-11-15T15:51:46","modified_gmt":"2021-11-15T15:51:46","slug":"developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces","status":"publish","type":"post","link":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/","title":{"rendered":"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces"},"content":{"rendered":"<p>&lt;&lt;(&#8230;) Les mutuelles sont d&rsquo;un int\u00e9r\u00eat ind\u00e9niable pour le bien-\u00eatre de nos populations. A cet \u00e9gard, je voudrais me r\u00e9jouir des acquis notables enregistr\u00e9s un peu partout dans les villages Gblo en mati\u00e8re de sant\u00e9, d&rsquo;\u00e9ducation et d&rsquo;infrastructures de base gr\u00e2ce \u00e0 l&rsquo;action conjugu\u00e9e des mutuelles et des cadres depuis plusieurs ann\u00e9es. Toutefois, de nombreux d\u00e9fis nous attendent sur la voie du d\u00e9veloppement. En effet, durant la campagne \u00e9lectorale des \u00e9lections l\u00e9gislatives de mars dernier, il m&rsquo;a \u00e9t\u00e9 donn\u00e9 de constater que des probl\u00e8mes \u00e9l\u00e9mentaires dans nos villages peinent \u00e0 \u00eatre r\u00e9solus dans la plupart de ces villages, notamment, l&rsquo;inexistence de centres de sant\u00e9 dans beaucoup de villages, l&rsquo;existence encore au XXI\u00e8 d&rsquo;\u00e9coles en paillote, le faible taux de scolarisation des enfants notamment de la gente f\u00e9minine, les probl\u00e8mes d&rsquo;adduction en eau potable, d&rsquo;\u00e9lectrification domestique, la d\u00e9gradation de nos voies&gt;&gt; a relev\u00e9 Assahor\u00e9 Konan Jacques, D\u00e9put\u00e9 de Diabo-Languibonou.<\/p>\n<p>C&rsquo;\u00e9tait lors d&rsquo;une r\u00e9union d&rsquo;\u00e9changes des cadres et Chefs canton Gblo qu&rsquo;il organis\u00e9e ce dimanche 14 novembre 2021 \u00e0 la biblioth\u00e8que nationale, au Plateau.<\/p>\n<p>Pour l&rsquo;honorable Assahor\u00e9 Konan Jacques, il se pose \u00e9videmment, au regard des difficult\u00e9s sociales, la question de la strat\u00e9gie que nous devons adopter pour sortir, \u00e0 tr\u00e8s court terme, notre localit\u00e9 de cette situation.<\/p>\n<p>&lt;&lt; L&rsquo; union fait la force. Nous attendons f\u00e9d\u00e9rer nos forces, nos \u00e9nergies au lieu de les \u00e9mietter dans le cadre des mutuelles par village ; f\u00e9d\u00e9rer nos \u00e9nergies pour que nous puissions avoir un \u00e9lan d&rsquo;ensemble, pour apporter une solution aux probl\u00e8mes sociaux de notre r\u00e9gion&gt;&gt; a indiqu\u00e9 le fils de Boukebo.<\/p>\n<p>Puis de pr\u00e9ciser qu&rsquo;un livre blanc permettant de faire l&rsquo;inventaire exhaustif de ces probl\u00e8mes est en train d&rsquo;\u00eatre \u00e9crit afin de commencer \u00e0 r\u00e9gler un \u00e0 un ces probl\u00e8mes.<br \/>\nUn draft de ce livre blanc disponible d&rsquo;ici la fin de l&rsquo;ann\u00e9e sera remis \u00e0 tous les pr\u00e9sidents de mutuelles de sorte \u00e0 pouvoir peaufiner le document.<\/p>\n<p>Aussi a-t-il invit\u00e9 les cadres \u00e0 l&rsquo;union et \u00e0 \u00e9viter les conflits de leadership quelle que soit leur appartenance politique. &lt;&lt; Les palabres n&rsquo;ont jamais apport\u00e9 le d\u00e9veloppement. Les conflits de leadership nous tirent vers la guerre. Il faut qu&rsquo;on soit soud\u00e9. Le groupe est toujours plus fort que le fort du groupe&gt;&gt; a estim\u00e9 le Directeur G\u00e9n\u00e9ral du Tr\u00e9sor et de la comptabilit\u00e9 publique.<\/p>\n<p>Assohor\u00e9 Konan Jacques a, par ailleurs, appel\u00e9 ses parents et le peuple Gblo \u00e0 se mobiliser pour prendre part au recensement g\u00e9n\u00e9ral de la population et de l&rsquo;habitat (RGPH) qui \u00ab\u00a0est vraiment un sujet important\u00a0\u00bb.<br \/>\nA cet effet, il a annonc\u00e9 la tenue de deux r\u00e9unions de sensibilisation ( une r\u00e9union, le vendredi 19 novembre prochain \u00e0 Languibonou et une autre, le samedi 20 novembre \u00e0 Diabo).<\/p>\n<p>L&rsquo;objectif de cette importante rencontre d&rsquo;informations de ce jour qui a enregistr\u00e9 la participation de plusieurs chefs canton, pr\u00e9sidents de mutuelle, cadres Gblo est, selon l&rsquo;honorable Assahor\u00e9 Konan Jacques, de se conna\u00eetre, remercier les populations, les exhorter \u00e0 continuer dans cette dynamique, \u00e0 faire confiance au Pr\u00e9sident Allassane Ouattara et faire en sorte que la r\u00e9gion sorte de \u00ab\u00a0l&rsquo;orni\u00e8re\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c9lu D\u00e9put\u00e9 sous la banni\u00e8re RHDP au soir des \u00e9lections l\u00e9gislatives du 06 mars dernier dans la circonscription de Diabo-Languibonou, Assahor\u00e9 Konan Jacques a d\u00e9j\u00e0 sillonn\u00e9 67 villages sur les 113 villages Gblo pour remercier ses parents qui lui ont fait confiance.<\/p>\n<p>&nbsp;<\/p>\n<p>Sunday ALAIN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&lt;&lt;(&#8230;) Les mutuelles sont d&rsquo;un int\u00e9r\u00eat ind\u00e9niable pour le bien-\u00eatre de nos populations. A cet \u00e9gard, je voudrais me r\u00e9jouir des acquis notables enregistr\u00e9s un peu partout dans les villages Gblo en mati\u00e8re de sant\u00e9, d&rsquo;\u00e9ducation et d&rsquo;infrastructures de base gr\u00e2ce \u00e0 l&rsquo;action conjugu\u00e9e des mutuelles et des cadres depuis plusieurs ann\u00e9es. Toutefois, de nombreux [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3130,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces - Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces - Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale\" \/>\n<meta property=\"og:description\" content=\"&lt;&lt;(&#8230;) Les mutuelles sont d&rsquo;un int\u00e9r\u00eat ind\u00e9niable pour le bien-\u00eatre de nos populations. A cet \u00e9gard, je voudrais me r\u00e9jouir des acquis notables enregistr\u00e9s un peu partout dans les villages Gblo en mati\u00e8re de sant\u00e9, d&rsquo;\u00e9ducation et d&rsquo;infrastructures de base gr\u00e2ce \u00e0 l&rsquo;action conjugu\u00e9e des mutuelles et des cadres depuis plusieurs ann\u00e9es. Toutefois, de nombreux [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/\" \/>\n<meta property=\"og:site_name\" content=\"Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T14:48:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-15T15:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amanien.info\/news\/wp-content\/uploads\/2021\/11\/thumbnail-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"809\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Germain Ndri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Germain Ndri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/\"},\"author\":{\"name\":\"Germain Ndri\",\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/#\\\/schema\\\/person\\\/b21093345753a1a98242d505bd894f42\"},\"headline\":\"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces\",\"datePublished\":\"2021-11-15T14:48:58+00:00\",\"dateModified\":\"2021-11-15T15:51:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/\"},\"wordCount\":652,\"image\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/thumbnail-3.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/\",\"url\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/\",\"name\":\"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces - Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/thumbnail-3.jpg\",\"datePublished\":\"2021-11-15T14:48:58+00:00\",\"dateModified\":\"2021-11-15T15:51:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/#\\\/schema\\\/person\\\/b21093345753a1a98242d505bd894f42\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/thumbnail-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/thumbnail-3.jpg\",\"width\":1080,\"height\":809},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/\",\"name\":\"Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale\",\"description\":\"L&#039;actualit\u00e9 Ivoirienne et Internationale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/#\\\/schema\\\/person\\\/b21093345753a1a98242d505bd894f42\",\"name\":\"Germain Ndri\",\"url\":\"https:\\\/\\\/www.amanien.info\\\/news\\\/author\\\/amanien-infos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces - Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces - Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale","og_description":"&lt;&lt;(&#8230;) Les mutuelles sont d&rsquo;un int\u00e9r\u00eat ind\u00e9niable pour le bien-\u00eatre de nos populations. A cet \u00e9gard, je voudrais me r\u00e9jouir des acquis notables enregistr\u00e9s un peu partout dans les villages Gblo en mati\u00e8re de sant\u00e9, d&rsquo;\u00e9ducation et d&rsquo;infrastructures de base gr\u00e2ce \u00e0 l&rsquo;action conjugu\u00e9e des mutuelles et des cadres depuis plusieurs ann\u00e9es. Toutefois, de nombreux [&hellip;]","og_url":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/","og_site_name":"Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale","article_published_time":"2021-11-15T14:48:58+00:00","article_modified_time":"2021-11-15T15:51:46+00:00","og_image":[{"width":1080,"height":809,"url":"https:\/\/www.amanien.info\/news\/wp-content\/uploads\/2021\/11\/thumbnail-3.jpg","type":"image\/jpeg"}],"author":"Germain Ndri","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Germain Ndri","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/#article","isPartOf":{"@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/"},"author":{"name":"Germain Ndri","@id":"https:\/\/www.amanien.info\/news\/#\/schema\/person\/b21093345753a1a98242d505bd894f42"},"headline":"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces","datePublished":"2021-11-15T14:48:58+00:00","dateModified":"2021-11-15T15:51:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/"},"wordCount":652,"image":{"@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amanien.info\/news\/wp-content\/uploads\/2021\/11\/thumbnail-3.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/","url":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/","name":"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces - Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale","isPartOf":{"@id":"https:\/\/www.amanien.info\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/#primaryimage"},"image":{"@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/#primaryimage"},"thumbnailUrl":"https:\/\/www.amanien.info\/news\/wp-content\/uploads\/2021\/11\/thumbnail-3.jpg","datePublished":"2021-11-15T14:48:58+00:00","dateModified":"2021-11-15T15:51:46+00:00","author":{"@id":"https:\/\/www.amanien.info\/news\/#\/schema\/person\/b21093345753a1a98242d505bd894f42"},"breadcrumb":{"@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/#primaryimage","url":"https:\/\/www.amanien.info\/news\/wp-content\/uploads\/2021\/11\/thumbnail-3.jpg","contentUrl":"https:\/\/www.amanien.info\/news\/wp-content\/uploads\/2021\/11\/thumbnail-3.jpg","width":1080,"height":809},{"@type":"BreadcrumbList","@id":"https:\/\/www.amanien.info\/news\/developpement-le-depute-de-diabo-languibonou-assahore-konan-jacques-releve-les-defis-de-sa-localite-et-invite-les-cadres-gblo-a-federer-leurs-energies-et-leurs-forces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.amanien.info\/news\/"},{"@type":"ListItem","position":2,"name":"D\u00e9veloppement : Le D\u00e9put\u00e9 de Diabo-Languibonou, Assahor\u00e9 Konan Jacques rel\u00e8ve les d\u00e9fis de sa localit\u00e9 et invite les cadres Gblo \u00e0 f\u00e9d\u00e9rer leurs \u00e9nergies et leurs forces"}]},{"@type":"WebSite","@id":"https:\/\/www.amanien.info\/news\/#website","url":"https:\/\/www.amanien.info\/news\/","name":"Amanien| L&#039;actualit\u00e9 Ivoirienne et Internationale","description":"L&#039;actualit\u00e9 Ivoirienne et Internationale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amanien.info\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.amanien.info\/news\/#\/schema\/person\/b21093345753a1a98242d505bd894f42","name":"Germain Ndri","url":"https:\/\/www.amanien.info\/news\/author\/amanien-infos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/posts\/3129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/comments?post=3129"}],"version-history":[{"count":1,"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/posts\/3129\/revisions"}],"predecessor-version":[{"id":3131,"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/posts\/3129\/revisions\/3131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/media\/3130"}],"wp:attachment":[{"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/media?parent=3129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/categories?post=3129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amanien.info\/news\/wp-json\/wp\/v2\/tags?post=3129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}